{"id":449,"date":"2014-08-24T19:00:21","date_gmt":"2014-08-24T17:00:21","guid":{"rendered":"http:\/\/darrigan.net\/blog\/?p=449"},"modified":"2020-04-30T12:50:49","modified_gmt":"2020-04-30T10:50:49","slug":"premiere-recolte-de-miel","status":"publish","type":"post","link":"https:\/\/darrigan.net\/blog\/premiere-recolte-de-miel\/","title":{"rendered":"Premi\u00e8re r\u00e9colte de miel"},"content":{"rendered":"<p>Une seule ruche a rempli une hausse de miel. Je n&rsquo;ai extrait que 4 cadres, les mieux opercul\u00e9s parmi les 9. Petite r\u00e9colte : 5,5 kg.<!--more--><\/p>\n<p>Les pots sont st\u00e9rilis\u00e9s \u00e0 l&rsquo;eau bouillante (comme pour les confitures).<\/p>\n<p>Le miel \u00ab\u00a0du jardin\u00a0\u00bb, un r\u00e9gal ! Le meilleur, bien s\u00fbr. Rien \u00e0 voir avec le miel de supermarch\u00e9.<\/p>\n<div id=\"attachment_450\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Miel-coulant.jpg\"><img aria-describedby=\"caption-attachment-450\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-450\" src=\"http:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Miel-coulant.jpg\" alt=\"Mise en pot.\" width=\"500\" height=\"1023\" srcset=\"https:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Miel-coulant.jpg 500w, https:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Miel-coulant-146x300.jpg 146w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-450\" class=\"wp-caption-text\">Mise en pot.<\/p><\/div>\n<div id=\"attachment_451\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Pots-miel.jpg\"><img aria-describedby=\"caption-attachment-451\" decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-451\" src=\"http:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Pots-miel.jpg\" alt=\"La r\u00e9colte en pot\" width=\"500\" height=\"289\" srcset=\"https:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Pots-miel.jpg 500w, https:\/\/darrigan.net\/blog\/wp-content\/uploads\/2014\/09\/Pots-miel-300x173.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-451\" class=\"wp-caption-text\">La r\u00e9colte en pot.<\/p><\/div>\n<p>Merci mes abeilles\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une seule ruche a rempli une hausse de miel. Je n&rsquo;ai extrait que 4 cadres, les mieux opercul\u00e9s parmi les 9. Petite r\u00e9colte : 5,5 kg.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[6,28],"_links":{"self":[{"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/posts\/449"}],"collection":[{"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/comments?post=449"}],"version-history":[{"count":2,"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/posts\/449\/revisions"}],"predecessor-version":[{"id":453,"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/posts\/449\/revisions\/453"}],"wp:attachment":[{"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/media?parent=449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/categories?post=449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/darrigan.net\/blog\/wp-json\/wp\/v2\/tags?post=449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}